{"id":2797,"date":"2026-05-08T09:32:58","date_gmt":"2026-05-08T09:32:58","guid":{"rendered":"https:\/\/tridashthailand.com\/?page_id=2797"},"modified":"2026-05-08T10:30:50","modified_gmt":"2026-05-08T10:30:50","slug":"race-rules","status":"publish","type":"page","link":"https:\/\/tridashthailand.com\/th\/race-rules\/","title":{"rendered":"Race Rules"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2797\" class=\"elementor elementor-2797\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e218411 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"e218411\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61ab476\" data-id=\"61ab476\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50abb6a elementor-widget elementor-widget-image\" data-id=\"50abb6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1981\" height=\"494\" src=\"https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero.png\" class=\"attachment-full size-full wp-image-2799\" alt=\"\" srcset=\"https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero.png 1981w, https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero-300x75.png 300w, https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero-1024x255.png 1024w, https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero-768x192.png 768w, https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero-1536x383.png 1536w, https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero-18x4.png 18w, https:\/\/tridashthailand.com\/wp-content\/uploads\/2026\/05\/race-rules-hero-700x175.png 700w\" sizes=\"(max-width: 1981px) 100vw, 1981px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65240b38 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"65240b38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75385fd2\" data-id=\"75385fd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38524b2e elementor-widget elementor-widget-heading\" data-id=\"38524b2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e35\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55bead96 elementor-widget elementor-widget-spacer\" data-id=\"55bead96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec5a007 elementor-widget elementor-widget-text-editor\" data-id=\"2ec5a007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"font-family: 'Montserrat', sans-serif;\"><ul><li>\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e08\u0e30\u0e40\u0e0a\u0e47\u0e04\u0e2d\u0e34\u0e19\u0e40\u0e02\u0e49\u0e32\u0e08\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49<\/li><li>\u0e15\u0e34\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e15\u0e2d\u0e19\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e48\u0e07\u00a0<\/li><li>\u0e15\u0e34\u0e14\u0e0a\u0e34\u0e1e\u0e08\u0e31\u0e1a\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e49\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e15\u0e31\u0e27<\/li><li>\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e17\u0e34\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e48\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e08\u0e38\u0e14\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2f \u0e08\u0e30\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e01\u0e23\u0e13\u0e35\u0e2a\u0e39\u0e0d\u0e2b\u0e32\u0e22<\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d07b60 elementor-widget elementor-widget-spacer\" data-id=\"8d07b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff7ab2a elementor-widget elementor-widget-heading\" data-id=\"ff7ab2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-516d29f elementor-widget elementor-widget-text-editor\" data-id=\"516d29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"font-family: 'Montserrat', sans-serif;\"><ul><li>\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e15\u0e23\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e41\u0e1e\u0e47\u0e04\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e1a\u0e19\u0e15\u0e31\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e48\u0e19\u0e40\u0e02\u0e49\u0e32\u0e08\u0e38\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e15\u0e31\u0e27\u0e17\u0e35\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33<\/li><li>\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e23\u0e13\u0e35\u0e41\u0e0b\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e22\u0e2a\u0e27\u0e19 \u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e48\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19<\/li><li>\u0e19\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07<\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3988522 elementor-widget elementor-widget-spacer\" data-id=\"3988522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbcfdb9 elementor-widget elementor-widget-heading\" data-id=\"dbcfdb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ace560 elementor-widget elementor-widget-text-editor\" data-id=\"8ace560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"font-family: 'Montserrat', sans-serif;\"><ul><li>\u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e02\u0e36\u0e49\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e2b\u0e21\u0e27\u0e01 \u0e15\u0e31\u0e14\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e41\u0e02\u0e48\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19<\/li><li>\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01 Transition<\/li><li>\u0e02\u0e36\u0e49\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e0b\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e16\u0e19\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e21\u0e31\u0e14\u0e23\u0e30\u0e27\u0e31\u0e07\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e48\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e41\u0e02\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e08\u0e23\u0e32\u0e08\u0e23\u0e02\u0e27\u0e32\u0e41\u0e25\u0e49\u0e27<\/li><li>\u0e02\u0e35\u0e48\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e08\u0e23\u0e32\u0e08\u0e23\u0e0b\u0e49\u0e32\u0e22\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e23\u0e13\u0e35\u0e41\u0e0b\u0e07 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e2d\u0e07\u0e08\u0e23\u0e32\u0e08\u0e23\u0e02\u0e27\u0e32\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e23\u0e30\u0e0a\u0e34\u0e14\u0e15\u0e31\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e30\u0e42\u0e01\u0e19\u0e27\u0e48\u0e32 \u201con your right\u201d \u0e02\u0e13\u0e30\u0e41\u0e0b\u0e07<\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3df639 elementor-widget elementor-widget-spacer\" data-id=\"e3df639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19021a9 elementor-widget elementor-widget-heading\" data-id=\"19021a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e2b\u0e49\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e34\u0e14\u0e15\u0e31\u0e27 (drafting zone)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9da91a elementor-widget elementor-widget-text-editor\" data-id=\"e9da91a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"font-family: 'Montserrat', sans-serif;\"><ul><li>\u0e25\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e0b\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e16\u0e19\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e23\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e47\u0e19\u0e40\u0e02\u0e49\u0e32\u0e08\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19<\/li><li>\u0e19\u0e31\u0e1a\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07<\/li><li>\u0e2b\u0e49\u0e32\u0e21\u0e43\u0e2a\u0e48\u0e2b\u0e39\u0e1f\u0e31\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19<\/li><li>\u0e2a\u0e27\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e02\u0e13\u0e30\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19<\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bed769 elementor-widget elementor-widget-spacer\" data-id=\"0bed769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e34038f elementor-widget elementor-widget-heading\" data-id=\"e34038f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e27\u0e34\u0e48\u0e07<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33fe32a elementor-widget elementor-widget-text-editor\" data-id=\"33fe32a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"font-family: 'Montserrat', sans-serif;\">\n<ul>\n<li>\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e23\u0e30\u0e22\u0e30 \u0e25\u0e2d\u0e07 \u0e41\u0e14\u0e0a \u0e41\u0e25\u0e30 \u0e41\u0e14\u0e0a \u0e08\u0e30\u0e27\u0e34\u0e48\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e23\u0e2d\u0e1a\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e19\u0e16\u0e19\u0e19\u0e02\u0e32\u0e40\u0e02\u0e49\u0e32-\u0e2d\u0e2d\u0e01 (<u>\u0e40\u0e25\u0e35\u0e49\u0e22\u0e27\u0e0b\u0e49\u0e32\u0e22<\/u> \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19)<\/li>\n<li>\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e23\u0e30\u0e22\u0e30\u0e21\u0e34\u0e19\u0e34 \u0e41\u0e14\u0e0a \u0e08\u0e30\u0e27\u0e34\u0e48\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e23\u0e2d\u0e1a\u0e40\u0e25\u0e47\u0e01 (<u>\u0e40\u0e25\u0e35\u0e49\u0e22\u0e27\u0e02\u0e27\u0e32<\/u> \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19)<\/li>\n<li>\u0e19\u0e31\u0e1a\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07<\/li>\n<li>\u0e2b\u0e49\u0e32\u0e21\u0e43\u0e2a\u0e48\u0e2b\u0e39\u0e1f\u0e31\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e27\u0e34\u0e48\u0e07<\/li>\n<li>\u0e2a\u0e27\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e02\u0e13\u0e30\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19<\/li>\n<li>\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e16\u0e2d\u0e14\u0e0a\u0e34\u0e1e\u0e08\u0e31\u0e1a\u0e40\u0e27\u0e25\u0e32\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e37\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e0a\u0e31\u0e22<\/li>\n<\/ul>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe68aa elementor-widget elementor-widget-spacer\" data-id=\"4fe68aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>In order to facilitate a safe racing environment we have come up with the following distancing and hygiene rules: Athletes can only check in to the transition area according to the scheduled times. Please arrive on time. Wear your bib number for the bike and&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"content-type":"","footnotes":""},"class_list":["post-2797","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/pages\/2797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/comments?post=2797"}],"version-history":[{"count":7,"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/pages\/2797\/revisions"}],"predecessor-version":[{"id":2812,"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/pages\/2797\/revisions\/2812"}],"wp:attachment":[{"href":"https:\/\/tridashthailand.com\/th\/wp-json\/wp\/v2\/media?parent=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}